{"id":33455,"date":"2024-04-04T16:17:23","date_gmt":"2024-04-04T14:17:23","guid":{"rendered":"https:\/\/dhl-freight-connections.com\/logistics-dictionary\/electric-stacker\/"},"modified":"2024-04-04T16:17:25","modified_gmt":"2024-04-04T14:17:25","slug":"electric-stacker","status":"publish","type":"logistics-dictionary","link":"https:\/\/dhl-freight-connections.com\/en\/logistics-dictionary\/electric-stacker\/","title":{"rendered":"Electric Stacker"},"content":{"rendered":"","protected":false},"featured_media":31267,"template":"","class_list":["post-33455","logistics-dictionary","type-logistics-dictionary","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dhl-freight-connections.com\/en\/wp-json\/wp\/v2\/logistics-dictionary\/33455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dhl-freight-connections.com\/en\/wp-json\/wp\/v2\/logistics-dictionary"}],"about":[{"href":"https:\/\/dhl-freight-connections.com\/en\/wp-json\/wp\/v2\/types\/logistics-dictionary"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dhl-freight-connections.com\/en\/wp-json\/wp\/v2\/media\/31267"}],"wp:attachment":[{"href":"https:\/\/dhl-freight-connections.com\/en\/wp-json\/wp\/v2\/media?parent=33455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}